{"id":5,"count":3,"description":"","link":"http:\/\/www.flamenco-carmendetorres.com\/estudio\/category\/classes\/","name":"Classes","slug":"classes","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.flamenco-carmendetorres.com\/estudio\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.flamenco-carmendetorres.com\/estudio\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.flamenco-carmendetorres.com\/estudio\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.flamenco-carmendetorres.com\/estudio\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}